{"id":327,"count":3,"description":"","link":"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/","name":"Desain Proyek","slug":"desain-proyek","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desain Proyek Archives - Git Aset Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desain Proyek Archives - Git Aset Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/\" \/>\n<meta property=\"og:site_name\" content=\"Git Aset Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/category\\\/desain-proyek\\\/\",\"url\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/category\\\/desain-proyek\\\/\",\"name\":\"Desain Proyek Archives - Git Aset Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/category\\\/desain-proyek\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/category\\\/desain-proyek\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desain Proyek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/\",\"name\":\"Git Aset Blog\",\"description\":\"Tren Desain, Inspirasi, Tips &amp; Trick\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gitaset.co\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desain Proyek Archives - Git Aset Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/","og_locale":"en_US","og_type":"article","og_title":"Desain Proyek Archives - Git Aset Blog","og_url":"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/","og_site_name":"Git Aset Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/","url":"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/","name":"Desain Proyek Archives - Git Aset Blog","isPartOf":{"@id":"https:\/\/gitaset.co\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/gitaset.co\/blog\/category\/desain-proyek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gitaset.co\/blog\/"},{"@type":"ListItem","position":2,"name":"Desain Proyek"}]},{"@type":"WebSite","@id":"https:\/\/gitaset.co\/blog\/#website","url":"https:\/\/gitaset.co\/blog\/","name":"Git Aset Blog","description":"Tren Desain, Inspirasi, Tips &amp; Trick","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gitaset.co\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/gitaset.co\/blog\/wp-json\/wp\/v2\/categories\/327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gitaset.co\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/gitaset.co\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/gitaset.co\/blog\/wp-json\/wp\/v2\/posts?categories=327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}